{"id":428,"date":"2022-04-06T09:25:25","date_gmt":"2022-04-06T12:25:25","guid":{"rendered":"https:\/\/academyulianov.com\/?p=428"},"modified":"2022-04-06T09:25:27","modified_gmt":"2022-04-06T12:25:27","slug":"defi","status":"publish","type":"post","link":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/","title":{"rendered":"DEFI"},"content":{"rendered":"\n<p>O QUE \u00c9 DEFI ?<\/p>\n\n\n\n<p>&nbsp;A evolu\u00e7\u00e3o do DeFi simplificou os servi\u00e7os financeiros juntamente com o processo de obten\u00e7\u00e3o de retornos favor\u00e1veis \u200b\u200bsobre investimentos em ativos digitais. No entanto, voc\u00ea tamb\u00e9m deve lembrar que o DeFi n\u00e3o oferece nenhum esquema de &#8216;enriquecimento r\u00e1pido&#8217; para aumentar o valor de seus ativos. &nbsp;<\/p>\n\n\n\n<p>&nbsp;DEFI na tradu\u00e7\u00e3o livre significa&nbsp; FINAN\u00c7AS DESCENTRALIZADAS que &nbsp;s\u00e3o onde o dinheiro e a tecnologia se encontram, sem intermedi\u00e1rios. \u00c9 um novo sistema financeiro sendo constru\u00eddo com tecnologia blockchain de c\u00f3digo aberto , que s\u00e3o regidas e executadas de forma totalmente descentralizada e p\u00fablica e sem bancos. Uma rede aberta, global e interconectada para transa\u00e7\u00f5es e armazenamento de valor.<\/p>\n\n\n\n<p>O n\u00edvel de descentraliza\u00e7\u00e3o da Bitcoin n\u00e3o existe paralelo algum . O Bitcoin \u00e9 atualmente o \u00fanico que cumpre objetivamente todas essas caracter\u00edsticas , embora haja muitas conversas sobre o grau de descentraliza\u00e7\u00e3o em todas as suas caracter\u00edsticas, quando se fala de uma certa concentra\u00e7\u00e3o nos Pools de Minera\u00e7\u00e3o.<\/p>\n\n\n\n<p>ORIGEM<\/p>\n\n\n\n<p>Nick Szabo apresentou sua ideia de contratos inteligentes no ano de 1995. Isso \u00e9 13 anos antes da cria\u00e7\u00e3o do Bitcoin, uma ideia certamente \u00e0 frente de seu tempo.<\/p>\n\n\n\n<p>Bitcoin \u00e9 definitivamente a primeira plataforma DeFi do mundo. Mas a origem da ideia \u00e9 muito mais antiga.<\/p>\n\n\n\n<p>O Ethereum e seus contratos inteligentes permitiram que os desenvolvedores criassem qualquer coisa que pudessem imaginar em cima de um blockchain. E precisamente isso que come\u00e7ou como um experimento agora est\u00e1 se tornando um movimento por si s\u00f3, em um ecossistema financeiro descentralizado que movimenta bilh\u00f5es de d\u00f3lares todos os meses.<\/p>\n\n\n\n<p>CARACTERISTICAS DEFI:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>SEGURAN\u00c7A:<\/li><\/ul>\n\n\n\n<p>&nbsp;Isso se deve ao fato de usarem poderosas t\u00e9cnicas criptogr\u00e1ficas para garantir que a plataforma, o acesso e o uso da mesma possam ser realizados apenas por pessoas autorizadas.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>DESCENTRALIZA\u00c7AO<\/li><\/ul>\n\n\n\n<p>O maior potencial do DeFi \u00e9 seu alto n\u00edvel de descentraliza\u00e7\u00e3o. Ou seja, eles t\u00eam a capacidade de atuar sem a necessidade de uma cadeia burocr\u00e1tica se impor sobre as fun\u00e7\u00f5es da plataforma.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>SEM INTERMEDI\u00c1RIOS<\/li><\/ul>\n\n\n\n<p>&nbsp;Isso significa que a a\u00e7\u00e3o em uma plataforma \u00e9 direta entre o usu\u00e1rio e a pr\u00f3pria plataforma. Terceiros confi\u00e1veis \u200b\u200bs\u00e3o desnecess\u00e1rios porque essa tarefa ser\u00e1 realizada pelo blockchain. \u00c9 essa estrutura que acompanhar\u00e1 tudo de forma segura e imut\u00e1vel. As DEFIs permitem o acesso a servi\u00e7os financeiros a milh\u00f5es de pessoas que n\u00e3o s\u00e3o banc\u00e1rias. Esta \u00e9, sem d\u00favida, uma oportunidade de ouro para levar desenvolvimento e liberdade financeira a quem por diversos motivos n\u00e3o tem conseguido usufruir destes servi\u00e7os.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>TRANSPARENCIA<\/li><\/ul>\n\n\n\n<p>&nbsp;Sendo constru\u00eddo em software livre, cada linha de c\u00f3digo da plataforma \u00e9 audit\u00e1vel. Al\u00e9m disso, a mobiliza\u00e7\u00e3o de recursos \u00e9 audit\u00e1vel, pois todos ocorrem no blockchain.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>SEM FRONTEIRAS<\/li><\/ul>\n\n\n\n<p>Voc\u00ea pode estar em qualquer pa\u00eds do mundo e acessar seus servi\u00e7os sem problemas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O QUE \u00c9 DEFI ? &nbsp;A evolu\u00e7\u00e3o do DeFi simplificou os servi\u00e7os financeiros juntamente com o processo de obten\u00e7\u00e3o de retornos favor\u00e1veis \u200b\u200bsobre investimentos em ativos digitais. No entanto, voc\u00ea tamb\u00e9m deve lembrar que o DeFi n\u00e3o oferece nenhum esquema de &#8216;enriquecimento r\u00e1pido&#8217; para aumentar o valor de seus ativos. &nbsp; &nbsp;DEFI na tradu\u00e7\u00e3o livre &#8230; <a title=\"DEFI\" class=\"read-more\" href=\"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/\" aria-label=\"Read more about DEFI\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-defi-renda-passiva"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DEFI - Academy Ulianov<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DEFI - Academy Ulianov\" \/>\n<meta property=\"og:description\" content=\"O QUE \u00c9 DEFI ? &nbsp;A evolu\u00e7\u00e3o do DeFi simplificou os servi\u00e7os financeiros juntamente com o processo de obten\u00e7\u00e3o de retornos favor\u00e1veis \u200b\u200bsobre investimentos em ativos digitais. No entanto, voc\u00ea tamb\u00e9m deve lembrar que o DeFi n\u00e3o oferece nenhum esquema de &#8216;enriquecimento r\u00e1pido&#8217; para aumentar o valor de seus ativos. &nbsp; &nbsp;DEFI na tradu\u00e7\u00e3o livre ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/\" \/>\n<meta property=\"og:site_name\" content=\"Academy Ulianov\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-06T12:25:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-06T12:25:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/04\/Logo-Gestao-de-Processos-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/\"},\"author\":{\"name\":\"Fer\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/#\\\/schema\\\/person\\\/ccdf174a91d227e6c76483a8c4a52452\"},\"headline\":\"DEFI\",\"datePublished\":\"2022-04-06T12:25:25+00:00\",\"dateModified\":\"2022-04-06T12:25:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/\"},\"wordCount\":499,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/academyulianov.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo-Gestao-de-Processos-3.png\",\"articleSection\":[\"DEFI- RENDA PASSIVA\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/\",\"url\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/\",\"name\":\"DEFI - Academy Ulianov\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/academyulianov.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo-Gestao-de-Processos-3.png\",\"datePublished\":\"2022-04-06T12:25:25+00:00\",\"dateModified\":\"2022-04-06T12:25:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/#\\\/schema\\\/person\\\/ccdf174a91d227e6c76483a8c4a52452\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/academyulianov.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo-Gestao-de-Processos-3.png\",\"contentUrl\":\"https:\\\/\\\/academyulianov.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo-Gestao-de-Processos-3.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/04\\\/06\\\/defi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/academyulianov.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DEFI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/#website\",\"url\":\"https:\\\/\\\/academyulianov.com\\\/\",\"name\":\"Academy Ulianov\",\"description\":\"The world&#039;s biggest financial revolution is coming!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/academyulianov.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/#\\\/schema\\\/person\\\/ccdf174a91d227e6c76483a8c4a52452\",\"name\":\"Fer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g\",\"caption\":\"Fer\"},\"sameAs\":[\"https:\\\/\\\/academyulianov.com\"],\"url\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DEFI - Academy Ulianov","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/","og_locale":"en_US","og_type":"article","og_title":"DEFI - Academy Ulianov","og_description":"O QUE \u00c9 DEFI ? &nbsp;A evolu\u00e7\u00e3o do DeFi simplificou os servi\u00e7os financeiros juntamente com o processo de obten\u00e7\u00e3o de retornos favor\u00e1veis \u200b\u200bsobre investimentos em ativos digitais. No entanto, voc\u00ea tamb\u00e9m deve lembrar que o DeFi n\u00e3o oferece nenhum esquema de &#8216;enriquecimento r\u00e1pido&#8217; para aumentar o valor de seus ativos. &nbsp; &nbsp;DEFI na tradu\u00e7\u00e3o livre ... Read more","og_url":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/","og_site_name":"Academy Ulianov","article_published_time":"2022-04-06T12:25:25+00:00","article_modified_time":"2022-04-06T12:25:27+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/04\/Logo-Gestao-de-Processos-3.png","type":"image\/png"}],"author":"Fer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Fer","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/#article","isPartOf":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/"},"author":{"name":"Fer","@id":"https:\/\/academyulianov.com\/#\/schema\/person\/ccdf174a91d227e6c76483a8c4a52452"},"headline":"DEFI","datePublished":"2022-04-06T12:25:25+00:00","dateModified":"2022-04-06T12:25:27+00:00","mainEntityOfPage":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/"},"wordCount":499,"commentCount":0,"image":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/#primaryimage"},"thumbnailUrl":"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/04\/Logo-Gestao-de-Processos-3.png","articleSection":["DEFI- RENDA PASSIVA"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/","url":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/","name":"DEFI - Academy Ulianov","isPartOf":{"@id":"https:\/\/academyulianov.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/#primaryimage"},"image":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/#primaryimage"},"thumbnailUrl":"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/04\/Logo-Gestao-de-Processos-3.png","datePublished":"2022-04-06T12:25:25+00:00","dateModified":"2022-04-06T12:25:27+00:00","author":{"@id":"https:\/\/academyulianov.com\/#\/schema\/person\/ccdf174a91d227e6c76483a8c4a52452"},"breadcrumb":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/#primaryimage","url":"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/04\/Logo-Gestao-de-Processos-3.png","contentUrl":"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/04\/Logo-Gestao-de-Processos-3.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/academyulianov.com\/index.php\/2022\/04\/06\/defi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/academyulianov.com\/"},{"@type":"ListItem","position":2,"name":"DEFI"}]},{"@type":"WebSite","@id":"https:\/\/academyulianov.com\/#website","url":"https:\/\/academyulianov.com\/","name":"Academy Ulianov","description":"The world&#039;s biggest financial revolution is coming!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/academyulianov.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/academyulianov.com\/#\/schema\/person\/ccdf174a91d227e6c76483a8c4a52452","name":"Fer","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g","caption":"Fer"},"sameAs":["https:\/\/academyulianov.com"],"url":"https:\/\/academyulianov.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/posts\/428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/comments?post=428"}],"version-history":[{"count":1,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/posts\/428\/revisions"}],"predecessor-version":[{"id":430,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/posts\/428\/revisions\/430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/media\/429"}],"wp:attachment":[{"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/media?parent=428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/categories?post=428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/tags?post=428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}