{"id":527,"date":"2022-07-29T04:48:55","date_gmt":"2022-07-29T07:48:55","guid":{"rendered":"https:\/\/academyulianov.com\/?p=527"},"modified":"2022-08-08T14:00:29","modified_gmt":"2022-08-08T17:00:29","slug":"egld","status":"publish","type":"post","link":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/","title":{"rendered":"EGLD"},"content":{"rendered":"\n<p><a href=\"https:\/\/coinmarketcap.com\/currencies\/elrond-egld\/\">https:\/\/coinmarketcap.com\/currencies\/elrond-egld\/<\/a><\/p>\n\n\n\n<p>EGLD \u00e9 a moeda nativa  da Elrond que facilita o funcionamento de toda a rede. A utilidade da moeda eGLD na Elrond \u00e9 m\u00faltipla. Ele \u00e9 usado como parte do mecanismo de governan\u00e7a da plataforma, para recompensas de staking e validadores e como pagamento por transa\u00e7\u00f5es e contratos inteligentes. Usu\u00e1rios e desenvolvedores da plataforma pagam para usar a Elrond Network com a moeda eGLD, que serve como g\u00e1spara todo o ecossistema. A moeda eGLD foi projetada para uso com a Maiar Wallet propriet\u00e1ria da Elrond, que permite aos usu\u00e1rios enviar transa\u00e7\u00f5es quase instant\u00e2neas pela Elrond Network. Maiar oferece recursos de empr\u00e9stimo, empr\u00e9stimo, envio e recebimento, al\u00e9m de staking.<\/p>\n\n\n\n<p>Em dezembro de 2021, a oferta circulante de moedas eGLD era de 20 milh\u00f5es, com 57% delas bloqueadas no protocolo de recompensas de apostas da rede. Novas moedas eGLD ser\u00e3o lan\u00e7adas lentamente de acordo com seus contratos inteligentes nos pr\u00f3ximos 10 anos at\u00e9 que o fornecimento final de 31,4 milh\u00f5es de moedas eGLD seja alcan\u00e7ado.<\/p>\n\n\n\n<p>Elrond \u00e9 uma rede blockchain barata, eficiente e escal\u00e1vel que fornece utilidade para desenvolvedores de dApp e solu\u00e7\u00f5es corporativas.<\/p>\n\n\n\n<p>Lan\u00e7ado em julho de 2020, o blockchain Elrond foi projetado para fornecer descentraliza\u00e7\u00e3o, seguran\u00e7a e escalabilidade para aplicativos distribu\u00eddos e empresas. O projeto se concentra na interoperabilidade entre cadeias , no suporte ao desenvolvedor e na obten\u00e7\u00e3o de m\u00e1xima efici\u00eancia operacional. A Elrond Network se autodenomina blockchain em escala de internet, o que significa que foi projetada para lidar com a taxa de transfer\u00eancia transacional em p\u00e9 de igualdade com as principais plataformas da Internet, em oposi\u00e7\u00e3o \u00e0 taxa de transfer\u00eancia relativamente baixa associada a outras redes de blockchain. Para colocar o throughput da Elrond em perspectiva: a rede Bitcoin pode confirmar uma m\u00e9dia de 7 transa\u00e7\u00f5es por segundo (TPS) ; a equipe de criptografia da Elrond afirma que sua rede pode lidar com 15.000 TPS e a um custo de apenas um centavo por transa\u00e7\u00e3o.<\/p>\n\n\n\n<p>A Elrond alcan\u00e7a essa not\u00e1vel efici\u00eancia de rede com uma combina\u00e7\u00e3o inovadora de seu mecanismo de consenso de Prova de Participa\u00e7\u00e3o Segura sob medida, tecnologia de fragmenta\u00e7\u00e3o avan\u00e7ada , estrutura de rede de valida\u00e7\u00e3o e moeda Elrond eGold (eGLD) nativa .<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Prova de participa\u00e7\u00e3o segura (SPoS)<\/p>\n\n\n\n<p>A Elrond Network usa seu pr\u00f3prio algoritmo de consenso Proof -of- Stake (PoS) exclusivo chamado Secure Proof of Stake (SPoS), que apresenta v\u00e1rias inova\u00e7\u00f5es exclusivas. Na Rede Elrond, um n\u00f3 \u00e9 um servidor, smartphone ou computador que executa o software cliente do n\u00f3 Elrond para retransmitir e processar dados pela rede. Enquanto todas as redes PoS utilizam um sistema de n\u00f3s para transacionar dados e estabelecer consenso, a Elrond faz uso de tr\u00eas tipos espec\u00edficos de n\u00f3s.<\/p>\n\n\n\n<p>Inova\u00e7\u00f5es de Blockchain Sharding da Elrond<\/p>\n\n\n\n<p>A Elrond Network emprega o que \u00e9 chamado de Adaptive State Sharding , combinando tr\u00eas m\u00e9todos de sharding padronizados (sharding de rede, sharding de transa\u00e7\u00e3o e sharding de estado) em um sistema balanceado de alto desempenho. A fragmenta\u00e7\u00e3o de rede facilita a maneira como os n\u00f3s de rede s\u00e3o alocados e mapeados em fragmentos espec\u00edficos, e a fragmenta\u00e7\u00e3o de transa\u00e7\u00e3o \u00e9 usada para determinar a maneira como as transa\u00e7\u00f5es s\u00e3o mapeadas para fragmentos. A fragmenta\u00e7\u00e3o de estado, no entanto, \u00e9 a mais complexa \u2013 e \u00e9 o que diferencia a Elrond de sua concorr\u00eancia.<\/p>\n\n\n\n<p>Al\u00e9m disso, Elrond utiliza o que chama de Metachain para coordenar os v\u00e1rios fragmentos da rede. O Metachain opera em seu pr\u00f3prio shard especializado que se comunica diretamente com todos os outros shards para coordenar as opera\u00e7\u00f5es de cross-shard que permitem todo o ecossistema de criptografia Elrond.<\/p>\n\n\n\n<p>Casos de uso de Elrond<\/p>\n\n\n\n<p>O Elrond foi desenvolvido para oferecer suporte a tokens n\u00e3o fung\u00edveis (NFTs) e apresenta uma estrutura NFT chamada Smart Accounts. As contas inteligentes funcionam como uma conta em qualquer outra rede blockchain, mas com suporte para armazenamento de dados de valor-chave no n\u00edvel da conta. Eles permitem que os usu\u00e1rios armazenem grandes quantidades de informa\u00e7\u00f5es &#8211; como e-mails, endere\u00e7os de bitcoin, dados de identidade privada, dados de sa\u00fade, comprovante de cidadania, informa\u00e7\u00f5es de Know-Your-Customer (KYC) e muito mais &#8211; diretamente em sua conta da Elrond Network. Al\u00e9m disso, as contas inteligentes s\u00e3o projetadas para armazenar e provar a propriedade de ativos digitais sem usar a Elrond VM, resultando em menos incha\u00e7o nos contratos inteligentes que regem os fundos dos usu\u00e1rios.<\/p>\n\n\n\n<p>A Elrond est\u00e1 trabalhando para implantar os Elrond Standard Digital Tokens (ESDTs) &#8211; stablecoins tokenizados, ativos sint\u00e9ticos e moedas fiduci\u00e1rias que ser\u00e3o executadas na rede Elrond, mas n\u00e3o exigem funcionalidade de contrato inteligente. A escalabilidade e a velocidade da Elrond tamb\u00e9m preparam a rede para a funcionalidade com a Internet das Coisas (IoT) .<\/p>\n\n\n\n<p>As empresas que est\u00e3o explorando as redes blockchain como solu\u00e7\u00f5es de neg\u00f3cios querem plataformas que atendam \u00e0s suas necessidades mais urgentes. A Elrond Network fornece um protocolo blockchain eficiente, escal\u00e1vel, amig\u00e1vel ao desenvolvedor e barato que pode satisfazer muitas necessidades de empresas de grande escala. Com uma lista crescente de clientes corporativos de blockchain em todo o mundo, a Elrond est\u00e1 fornecendo solu\u00e7\u00f5es para troca de dados, IoT, servi\u00e7os financeiros e muito mais \u2013 mostrando que a ado\u00e7\u00e3o da rede Elrond pelos usu\u00e1rios est\u00e1 cada vez mais forte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elrond Network (EGLD): Uma Blockchain de Escala da Internet<\/p>\n","protected":false},"author":1,"featured_media":547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cripto-iniciantes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EGLD - Academy Ulianov<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EGLD - Academy Ulianov\" \/>\n<meta property=\"og:description\" content=\"Elrond Network (EGLD): Uma Blockchain de Escala da Internet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/\" \/>\n<meta property=\"og:site_name\" content=\"Academy Ulianov\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-29T07:48:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-08T17:00:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/07\/TVL-O-que-significa-valor-bloqueado-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/\"},\"author\":{\"name\":\"Fer\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/#\\\/schema\\\/person\\\/ccdf174a91d227e6c76483a8c4a52452\"},\"headline\":\"EGLD\",\"datePublished\":\"2022-07-29T07:48:55+00:00\",\"dateModified\":\"2022-08-08T17:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/\"},\"wordCount\":928,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/academyulianov.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/TVL-O-que-significa-valor-bloqueado-1.jpg\",\"articleSection\":[\"CRYPTO -INICIANTES\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/\",\"url\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/\",\"name\":\"EGLD - Academy Ulianov\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/academyulianov.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/TVL-O-que-significa-valor-bloqueado-1.jpg\",\"datePublished\":\"2022-07-29T07:48:55+00:00\",\"dateModified\":\"2022-08-08T17:00:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/#\\\/schema\\\/person\\\/ccdf174a91d227e6c76483a8c4a52452\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/#primaryimage\",\"url\":\"https:\\\/\\\/academyulianov.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/TVL-O-que-significa-valor-bloqueado-1.jpg\",\"contentUrl\":\"https:\\\/\\\/academyulianov.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/TVL-O-que-significa-valor-bloqueado-1.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/2022\\\/07\\\/29\\\/egld\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/academyulianov.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EGLD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/#website\",\"url\":\"https:\\\/\\\/academyulianov.com\\\/\",\"name\":\"Academy Ulianov\",\"description\":\"The world&#039;s biggest financial revolution is coming!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/academyulianov.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/academyulianov.com\\\/#\\\/schema\\\/person\\\/ccdf174a91d227e6c76483a8c4a52452\",\"name\":\"Fer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g\",\"caption\":\"Fer\"},\"sameAs\":[\"https:\\\/\\\/academyulianov.com\"],\"url\":\"https:\\\/\\\/academyulianov.com\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EGLD - Academy Ulianov","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/","og_locale":"en_US","og_type":"article","og_title":"EGLD - Academy Ulianov","og_description":"Elrond Network (EGLD): Uma Blockchain de Escala da Internet","og_url":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/","og_site_name":"Academy Ulianov","article_published_time":"2022-07-29T07:48:55+00:00","article_modified_time":"2022-08-08T17:00:29+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/07\/TVL-O-que-significa-valor-bloqueado-1.jpg","type":"image\/jpeg"}],"author":"Fer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Fer","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/#article","isPartOf":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/"},"author":{"name":"Fer","@id":"https:\/\/academyulianov.com\/#\/schema\/person\/ccdf174a91d227e6c76483a8c4a52452"},"headline":"EGLD","datePublished":"2022-07-29T07:48:55+00:00","dateModified":"2022-08-08T17:00:29+00:00","mainEntityOfPage":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/"},"wordCount":928,"commentCount":0,"image":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/#primaryimage"},"thumbnailUrl":"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/07\/TVL-O-que-significa-valor-bloqueado-1.jpg","articleSection":["CRYPTO -INICIANTES"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/","url":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/","name":"EGLD - Academy Ulianov","isPartOf":{"@id":"https:\/\/academyulianov.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/#primaryimage"},"image":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/#primaryimage"},"thumbnailUrl":"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/07\/TVL-O-que-significa-valor-bloqueado-1.jpg","datePublished":"2022-07-29T07:48:55+00:00","dateModified":"2022-08-08T17:00:29+00:00","author":{"@id":"https:\/\/academyulianov.com\/#\/schema\/person\/ccdf174a91d227e6c76483a8c4a52452"},"breadcrumb":{"@id":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/#primaryimage","url":"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/07\/TVL-O-que-significa-valor-bloqueado-1.jpg","contentUrl":"https:\/\/academyulianov.com\/wp-content\/uploads\/2022\/07\/TVL-O-que-significa-valor-bloqueado-1.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/academyulianov.com\/index.php\/2022\/07\/29\/egld\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/academyulianov.com\/"},{"@type":"ListItem","position":2,"name":"EGLD"}]},{"@type":"WebSite","@id":"https:\/\/academyulianov.com\/#website","url":"https:\/\/academyulianov.com\/","name":"Academy Ulianov","description":"The world&#039;s biggest financial revolution is coming!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/academyulianov.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/academyulianov.com\/#\/schema\/person\/ccdf174a91d227e6c76483a8c4a52452","name":"Fer","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff61e0c720d3ae65f6abe4cd2c92a1492d1f6b2dc72b0a998c357c66ee1610eb?s=96&d=mm&r=g","caption":"Fer"},"sameAs":["https:\/\/academyulianov.com"],"url":"https:\/\/academyulianov.com\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/posts\/527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/comments?post=527"}],"version-history":[{"count":1,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/posts\/527\/revisions"}],"predecessor-version":[{"id":529,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/posts\/527\/revisions\/529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/media\/547"}],"wp:attachment":[{"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/media?parent=527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/categories?post=527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/academyulianov.com\/index.php\/wp-json\/wp\/v2\/tags?post=527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}